{"id":8139,"date":"2018-04-05T09:00:15","date_gmt":"2018-04-05T07:00:15","guid":{"rendered":"http:\/\/taschenfreak.de\/blog\/?p=8139"},"modified":"2018-03-30T12:53:41","modified_gmt":"2018-03-30T10:53:41","slug":"der-grosse-filtertaschentest-lowepro-sf-filter-pouch","status":"publish","type":"post","link":"https:\/\/taschenfreak.de\/blog\/2018\/04\/05\/der-grosse-filtertaschentest-lowepro-sf-filter-pouch\/","title":{"rendered":"Der gro\u00dfe Filtertaschentest &#8211; LOWEPRO S&#038;F FILTER POUCH"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=lqHLh59SzzQ\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8141 size-full\" src=\"https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro.jpg 1200w, https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro-300x169.jpg 300w, https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro-768x432.jpg 768w, https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>In der gro\u00dfen Filtertaschen-Test-Serie sind wir jetzt angekommen bei dem <strong>LOWEPRO S&amp;F FILTER POUCH.&nbsp;<\/strong>Schaut Euch das folgende <a href=\"https:\/\/www.youtube.com\/watch?v=lqHLh59SzzQ\">Video<\/a> dazu an.<\/p>\n<div class=\"jetpack-video-wrapper\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"> <\/p>\n<div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBjbGFzcz0ieW91dHViZS1wbGF5ZXIiIHdpZHRoPSI2NTAiIGhlaWdodD0iMzY2IiBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUtbm9jb29raWUuY29tL2VtYmVkL2xxSExoNTlTenpRP3ZlcnNpb249MyYjMDM4O3JlbD0xJiMwMzg7c2hvd3NlYXJjaD0wJiMwMzg7c2hvd2luZm89MSYjMDM4O2l2X2xvYWRfcG9saWN5PTEmIzAzODtmcz0xJiMwMzg7aGw9ZGUtREUmIzAzODthdXRvaGlkZT0yJiMwMzg7d21vZGU9dHJhbnNwYXJlbnQiIGFsbG93ZnVsbHNjcmVlbj0idHJ1ZSIgc3R5bGU9ImJvcmRlcjowOyIgc2FuZGJveD0iYWxsb3ctc2NyaXB0cyBhbGxvdy1zYW1lLW9yaWdpbiBhbGxvdy1wb3B1cHMgYWxsb3ctcHJlc2VudGF0aW9uIGFsbG93LXBvcHVwcy10by1lc2NhcGUtc2FuZGJveCI+PC9pZnJhbWU+\">\n<div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\">\n<div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/borlabs-cookie\/1\/yt_lqHLh59SzzQ_hqdefault.jpg')\"><\/div>\n<div class=\"brlbs-cmpnt-cb-main\">\n<div class=\"brlbs-cmpnt-cb-play-button\"><\/div>\n<div class=\"brlbs-cmpnt-cb-content\">\n<p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p>\n<p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div>\n<div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><\/span><\/div>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=lqHLh59SzzQ\">Direkt-Link zum Video<\/a><\/p>\n<p>Den <a href=\"http:\/\/www.christian-ohlig.de\/?p=6796\">DEEP-REVIEW<\/a> zur Rollei Filtertasche findet Ihr <a href=\"http:\/\/www.christian-ohlig.de\/?p=6796\">HIER<\/a> auf Christians Blog.<br \/>\n<a href=\"http:\/\/www.christian-ohlig.de\/?p=6796\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8168 size-full\" src=\"https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/Logo_Christian-Ohlig.png\" alt=\"\" width=\"250\" height=\"95\"><\/a><\/p>\n<p>Dort k\u00f6nnt Ihr die Tasche auch selbst bewerten. Wir sind sehr gespannt auf Eure Meinung.<\/p>\n<p>Die komplette Serie mit allen Beitr\u00e4gen findet Ihr in der neuen Kategorie &#8222;<a href=\"https:\/\/taschenfreak.de\/blog\/category\/filtertaschen\/\">Filtertaschen hier auf Taschenfreak<\/a>&#8222;.<\/p>\n<p>Bisher erschienen sind in der gro\u00dfen Filtertaschen-Test-Serie:<\/p>\n<ul>\n<li><a href=\"https:\/\/taschenfreak.de\/blog\/?p=8106\">Der Start der gro\u00dfen Filter-Serie<\/a><\/li>\n<li><a href=\"https:\/\/taschenfreak.de\/blog\/?p=8113\">LEE FILTER POUCH<\/a><\/li>\n<li><a href=\"https:\/\/taschenfreak.de\/blog\/?p=8118\">ROLLEI FILTERTASCHE 100<\/a><\/li>\n<li><a href=\"https:\/\/taschenfreak.de\/blog\/?p=8125\">TERRASCAPE FILTER BAG CLASSIC III<\/a><\/li>\n<li><a href=\"https:\/\/taschenfreak.de\/blog\/?p=8134\">NISI ALL IN ONE CASE<\/a><\/li>\n<\/ul>\n<p>Es folgen noch die folgenden Filtertaschen in dieser Serie:<\/p>\n<ul>\n<li>F-STOP GEAR FILTER CASE<\/li>\n<li>HAIDA FILTERTASCHE<\/li>\n<li>MINDSHIFTGEAR FILTER HIVE MINI<\/li>\n<li>TERRASCAPE SMALL ONE III<\/li>\n<li>MINDSHIFTGEAR FILTER HIVE<\/li>\n<li>&#8230; und unsere pers\u00f6nlichen TOP3-Filtertaschen<\/li>\n<\/ul>\n<p>Wir w\u00fcnschen Euch viel Spa\u00df bei dieser Serie und hoffen Euch bei der Auswahl einer geeigneten Filtertasche etwas geholfen zu haben.<\/p>\n<p>Sch\u00f6ne Gr\u00fc\u00dfe &#8211; Euer Taschenfreak &#8211; J\u00f6rg Langer<\/p>\n<hr>\n<p><strong>Bezugsquellen:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/amzn.to\/2pFv7ol\">LEE FILTER POUCH<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2IQf8LU\">ROLLEI FILTERTASCHE 100<\/a><\/li>\n<li><a href=\"https:\/\/terrascape.pt\/loja\/unkategorisiert\/pro-classic\/?lang=de\">TERRASCAPE FILTER BAG CLASSIC III<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2DVa7hB\">NISI ALL IN ONE CASE<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2I1iFpq\">LOWEPRO S&amp;F FILTER POUCH<\/a><\/li>\n<li><a href=\"https:\/\/www.ac-foto.com\/onlineshop\/v3\/?s=detail&amp;main=9339\">F-STOP GEAR FILTER CASE<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2uk43Qb\">HAIDA FILTERTASCHE<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2G9jUm5\">MINDSHIFTGEAR FILTER HIVE MINI<\/a><\/li>\n<li><a href=\"https:\/\/terrascape.pt\/loja\/unkategorisiert\/filter-bag-smallone\/?lang=de\">TERRASCAPE FILTER BAG SMALL ONE III<\/a><\/li>\n<li><a href=\"https:\/\/amzn.to\/2ulNhjC\">MINDSHIFTGEAR FILTER HIVE<\/a><\/li>\n<\/ul>\n<hr>\n<p><span style=\"font-size: 8pt;\">Hinweis zu WERBUNG:<\/span><\/p>\n<p><span style=\"font-size: 8pt;\">Meine Blogbeitr\u00e4ge und Videos sind Gluten-, Glukose- und Laktosefrei, k\u00f6nnen aber Spuren von Werbung beinhalten da ich die Artikel ab und zu kostenlos zur Verf\u00fcgung gestellt bekomme.<\/span><\/p>\n<p><span style=\"font-size: 8pt;\">Meine Meinung ist frei von kommerziellen Einfl\u00fcssen, kann aber Spuren von Sarkasmus oder Ironie beinhalten.<\/span><\/p>\n<p><span style=\"font-size: 8pt;\">Dieser Blog verfolgt keine kommerziellen Absichten. Die meisten mir zur Verf\u00fcgung gestellten Taschen verschenke ich oder verlose die f\u00fcr gute Zwecke. Meine treuen Leser wissen das seit Jahren. Ich betreibe diesen Blog aus Spa\u00df an der Sache und nicht aus kommerziellen Absichten. Das mag in der heutigen Zeit eher ungew\u00f6hnlich sein. Mit diesem Schock m\u00fcsst Ihr leider zurecht kommen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der gro\u00dfen Filtertaschen-Test-Serie sind wir jetzt angekommen bei dem LOWEPRO S&#038;F FILTER POUCH.\u00a0Schaut Euch das folgende Video dazu an.<\/p>\n","protected":false},"author":3,"featured_media":8140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[1908,52],"tags":[1923,1930,1039,1921,1931,1926,1788,1911,1924,1912,1927,1928,1918,1910,1925,1916,1913,1914,1054,1917,1929,1915,1919,1922,1920],"class_list":["post-8139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filtertaschen","category-zubehortasche","tag-100-system","tag-all-in-one-case","tag-christian-ohlig","tag-classic","tag-der-grosse-filtertaschen-test","tag-einsteckfilter","tag-f-stop-gear","tag-filter","tag-filter-100x150","tag-filter-bags","tag-filter-hive","tag-filter-hive-mini","tag-filter-poch","tag-filtertaschen","tag-flachfilter","tag-haida","tag-lee","tag-lee-filters","tag-lowepro","tag-mind-shift-gear","tag-nisi","tag-rollei","tag-sf-filter-pouch","tag-small-one","tag-terrascape"],"jetpack_featured_media_url":"https:\/\/taschenfreak.de\/blog\/wp-content\/uploads\/2018\/03\/2018-03-25-Filtertaschen-06-Lowepro-Banner.jpg","jetpack_shortlink":"https:\/\/wp.me\/p4GMND-27h","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/posts\/8139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/comments?post=8139"}],"version-history":[{"count":0,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/posts\/8139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/media\/8140"}],"wp:attachment":[{"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/media?parent=8139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/categories?post=8139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taschenfreak.de\/blog\/wp-json\/wp\/v2\/tags?post=8139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}